{"id":10589,"date":"2021-11-03T14:16:11","date_gmt":"2021-11-03T17:16:11","guid":{"rendered":"http:\/\/blog.topinmobiliario.com\/?p=10589"},"modified":"2021-11-03T14:16:11","modified_gmt":"2021-11-03T17:16:11","slug":"una-brujula-para-el-mercado-corporativo","status":"publish","type":"post","link":"http:\/\/blog.topinmobiliario.com\/index.php\/una-brujula-para-el-mercado-corporativo\/","title":{"rendered":"Una br\u00fajula para el mercado corporativo"},"content":{"rendered":"\n<p><strong>El bienestar y la inclusi\u00f3n son dos de los aspectos que cobraron relevancia en el \u00faltimo tiempo y que m\u00e1s valoran las personas al momento de volver a las nuevas oficinas. Datos de un informe.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.areas-digital.com.ar\/online\/nota_27282_1.jpg\"><img src=\"https:\/\/www.areas-digital.com.ar\/online\/thum_1_nota_27282_1.jpg\" alt=\"\" title=\"\"\/><\/a><\/figure>\n\n\n\n<p>Con el objetivo de crear un mapa de ruta hacia el futuro de los negocios inmobiliarios corporativos, CBRE present\u00f3 un informe con los nuevos par\u00e1metros y medidas que definir\u00e1n cu\u00e1l es la mejor manera de recibir a los empleados en la vuelta a las oficinas.<br><br>A partir de la implementaci\u00f3n de distintas herramientas &#8211; como talleres de descubrimiento, grupos de trabajo, entrevistas a accionistas claves y tours globales virtuales \u2013 se elabor\u00f3 un informe que presenta siete ideas clave para ofrecer una experiencia laboral \u00f3ptima.<br><br>Para empezar, se destaca la importancia de incentivar y ampliar la participaci\u00f3n en programas de bienestar y salud. El lugar de trabajo de una persona suele ser donde pasa la mayor parte de su d\u00eda, por lo que es fundamental innovar y apoyar el bienestar a trav\u00e9s no solo de caracter\u00edsticas arquitect\u00f3nicas pasivas, sino tambi\u00e9n de iniciativas activas de eventos y programas.<\/p>\n\n\n\n<p><img alt=\"\" src=\"http:\/\/www.areas-digital.com.ar\/online\/7229_6402.jpg\"><br><br>En segundo lugar, la calidad significativa de la tecnolog\u00eda a la hora de hacer reuniones virtuales. La calidad del audio, la vista de la habitaci\u00f3n, el flujo de conversaci\u00f3n y el intercambio de informaci\u00f3n son t\u00edpicas. El dise\u00f1o y la est\u00e9tica tambi\u00e9n son un factor importante para que los empleados puedan trabajar de manera presencial en las oficinas. En tercer lugar, se encuentra la hospitalidad. Los gerentes de operaciones, los recepcionistas y hasta la tecnolog\u00eda impactan la experiencia de empleado y visitante. La oficina, m\u00e1s que nunca, debe anticipar las necesidades del cliente y proporcionar comodidad y flexibilidad, para as\u00ed poder competir con el atractivo del trabajo remoto. Por su parte, la cultura y comunidad de una oficina son factores claves para la medici\u00f3n del \u00e9xito, aunque pueden ser dif\u00edciles de mesurar..<br><br>Una idea que destaca el informe y que estuvo muy presente en los \u00faltimos a\u00f1os es el coworking. Se plantea la opci\u00f3n de presentar estos espacios de oficina flexible como un beneficio para los empleados, en especial para aquellos que viven en zonas alejadas o que viajan constantemente de ciudad en ciudad visitando clientes.<br><br>Por \u00faltimo, los conceptos de diversidad, equidad eiInclusi\u00f3n, que son vitales para el \u00e9xito de las organizaciones. Los espacios de trabajo deben ser dise\u00f1ados para todas las personas, incluidas aquellas con discapacidades visibles o invisibles, individuos neurodiversos y todas las identidades.<\/p>\n\n\n\n<p><em>Mi\u00e9rcoles 25 de Agosto de 2021<\/em><br><em>Publicado en Indicadores y Finanzas de www.areas-digital.com.ar<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El bienestar y la inclusi\u00f3n son dos de los aspectos que cobraron relevancia en el \u00faltimo tiempo y que m\u00e1s valoran las personas al momento de volver a las nuevas oficinas. Datos de un informe. Con el objetivo de crear un mapa de ruta hacia el futuro de los negocios inmobiliarios corporativos, CBRE present\u00f3 un &hellip; <\/p>\n<p class=\"link-more\"><a href=\"http:\/\/blog.topinmobiliario.com\/index.php\/una-brujula-para-el-mercado-corporativo\/\" class=\"more-link\">Segu\u00ed leyendo<span class=\"screen-reader-text\"> &#8220;Una br\u00fajula para el mercado corporativo&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[828,5],"tags":[869,43],"_links":{"self":[{"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/posts\/10589"}],"collection":[{"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/comments?post=10589"}],"version-history":[{"count":1,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/posts\/10589\/revisions"}],"predecessor-version":[{"id":10590,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/posts\/10589\/revisions\/10590"}],"wp:attachment":[{"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/media?parent=10589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/categories?post=10589"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/tags?post=10589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}