{"id":3310,"date":"2011-05-02T19:45:37","date_gmt":"2011-05-02T19:45:37","guid":{"rendered":"http:\/\/blog.topinmobiliario.com\/?p=3310"},"modified":"2011-05-02T19:47:50","modified_gmt":"2011-05-02T19:47:50","slug":"palermo-fuerte-identidad","status":"publish","type":"post","link":"http:\/\/blog.topinmobiliario.com\/index.php\/palermo-fuerte-identidad\/","title":{"rendered":"Palermo Fuerte identidad"},"content":{"rendered":"<p><strong>En torno de la tradicional parroquia, frente a la plaza G\u00fcemes, el  crecimiento no se detiene y extiende sus l\u00edmites con alrededor de 30  proyectos de diversa magnitud. El precio de la incidencia de los  terrenos ronda los 700 d\u00f3lares el m2, pero puede alcanzar hasta 1100.<\/strong><\/p>\n<p>Cuando los vecinos remozaron con mucho verde el bulevar de la calle  Charcas y se inaugur\u00f3 Alto Palermo Shopping, en los a\u00f1os 90, comenz\u00f3 el  impulso debido a los desarrollos inmobiliarios en este barrio que hoy se  denomina Palermo Sensible, delimitado por las avenidas Scalabrini  Ortiz, Santa Fe y Coronel D\u00edaz y la calle Honduras. El auge que tom\u00f3 en  la \u00faltima d\u00e9cada con modernos edificios atrajo a numerosos nuevos  vecinos; las construcciones ya se extienden hacia el sur hasta Cabrera y  al este hasta Billinghurst. Hoy existen m\u00e1s de 30 nuevos  emprendimientos.<\/p>\n<p><!--more-->Al respecto, Roberto Rosa, R. Rosa &amp; Asociados SA,  comenta: &#8220;La zona era un espacio de oportunidades en el nivel  inmobiliario por estar compuesta por casas antiguas, bajas y PH, que  dieron paso a la construcci\u00f3n de buenos edificios que atraen a los  inversionistas, a los antiguos vecinos y a las familias del interior  para alojar a sus hijos que estudian en las universidades cercanas&#8221;.  Esta firma comercializa los desarrollos de Tecnourbana, que realiz\u00f3  varios en el lugar y ahora presenta dos nuevos, Icono G\u00fcemes e Icono  Honduras. El primero es a estrenar con una inversi\u00f3n de dos millones de  d\u00f3lares. El gerente del proyecto, el arquitecto Gast\u00f3n Fern\u00e1ndez Madero,  se\u00f1ala: &#8220;El edificio se caracteriza por su versatilidad, ideal para  distintos usos, renta, inversi\u00f3n, estudios o vivienda&#8221;. El segundo est\u00e1  en construcci\u00f3n.<\/p>\n<p>El acceso a numerosos medios de transporte, incluido el  subte, genera un sector privilegiado para vivir, por eso uno de los  socios de la inmobiliaria Shenk, una de las m\u00e1s antiguas con 90 a\u00f1os en  el barrio, Gregorio Berberian, refiere: &#8220;Estas 24 manzanas son muy  cotizadas en el mercado inmobiliario y se las considera como uno de los  lugares con mayor valor de reventa de la Capital, hay muchos pedidos de  terrenos para construir, pero es muy poca la oferta, por eso las viejas  propiedades aumentan sus valores&#8221;. Los terrenos, seg\u00fan la superficie y  su ubicaci\u00f3n, tienen una incidencia de 700 d\u00f3lares el m2, aunque los  lotes mayores pueden superar los 1100 d\u00f3lares el m2.<\/p>\n<p>En lo que era un taller mec\u00e1nico, en la esquina de  Scalabrini Ortiz y Costa Rica 4400, comienzan a levantar una obra que le  dar\u00e1 mayor jerarqu\u00eda y servicios a Palermo Sensible. Se trata del BF  SoHo. La desarrolladora Brody Friedman ide\u00f3 el primer edificio con  unidades hoteleras para suites y estudios profesionales, con  hidromasajes, adem\u00e1s del bar y el lobby abierto las 24 horas inspirado  en el SoHo neoyorquino. Con una inversi\u00f3n de tres millones de d\u00f3lares,  las 49 unidades hoteleras saldr\u00e1n a la venta desde 2500 d\u00f3lares el m2,  para ser utilizadas como residencias temporarias o para estudios  profesionales. &#8220;Las que se destinen a renta temporaria tendr\u00e1n una renta  de locaci\u00f3n de entre el 13 y el 17% anual en d\u00f3lares, dependiendo del  equipamiento&#8221;, estima Andr\u00e9s Brody, uno de los titulares de la firma.<\/p>\n<p>En Honduras al 3700 se construye Metro VIII, un  desarrollo de Metro Building, que invirti\u00f3 3.500.000 d\u00f3lares &#8220;para  dotarlo de calidad premium&#8221;, comenta An\u00edbal Montes h., gerente de la  comercializadora RG &#8211; Montes Propiedades.<\/p>\n<p>Con relaci\u00f3n a las unidades usadas para comprar, los  valores rondan entre 1800 y 2500 d\u00f3lares el m2, seg\u00fan caracter\u00edsticas y  variables.<\/p>\n<p><strong>Historia<\/strong><\/p>\n<p>La parroquia y el  moderno complejo educativo y religioso de la restaurada bas\u00edlica de la  Virgen de Guadalupe, en Mansilla y Serrano, junto a la plaza G\u00fcemes, que  est\u00e1 enfrente, encierran una identidad hist\u00f3rica y centenaria, adem\u00e1s  del bulevar Charcas, donde se dio el puntapi\u00e9 inicial a los desarrollos  inmobiliarios. Sin dejar de lado dos importantes caf\u00e9s que existieron  durante muchos a\u00f1os en las inmediaciones de la plaza, Sigi y Freud,  haciendo eco al nombre del barrio, ahora denominado Palermo Sensible.  Todo relacionado con la psicolog\u00eda, porque la Argentina es el pa\u00eds con  mayor cantidad de psic\u00f3logos por habitante del mundo, uno por cada 650, y  la ciudad de Buenos Aires concentra a\u00fan m\u00e1s, uno cada 120 habitantes,  siendo \u00e9sta la zona que alberga la mayor cantidad de psic\u00f3logos.<\/p>\n<p>Algo m\u00e1s, frente a la plaza se organizan numerosos  actos donde participa y colabora la gran mayor\u00eda de los vecinos. Tambi\u00e9n  algunos matrimonios, que se han unido frente al altar de la Virgen, han  decidido radicarse en el lugar y env\u00edan a sus hijos a esa misma  instituci\u00f3n. Otros acontecimientos, como conciertos y ferias, por  ejemplo, que se desarrollan en la plaza G\u00fcemes son recuerdos que los  habitantes del lugar asocian con la historia de cada familia, como lo  manifiesta Graciela M., joven vecina de un moderno desarrollo: &#8220;Mis  padres me criaron en una vieja casona de la calle Honduras hasta que la  vendieron para que se construyera un edificio, donde ellos viven ahora  en un departamento y yo en otro junto con mi esposo, y de aqu\u00ed nadie nos  mueve porque todo esto es como algo propio, es nuestra vida&#8221;.<\/p>\n<p><strong>ATRACCI\u00d3N TUR\u00cdSTICA<\/strong><\/p>\n<p>El  ritmo diurno del barrio, con los  alumnos de varios colegios instalados  en la zona, y los estudiantes de  la Universidad de Palermo y de la UTN,  m\u00e1s otros centros de estudios  de nivel terciario, que le otorgan un  tinte pintoresco, se contrapone  con la vida nocturna, que ofrece veladas  musicales en sus  caracter\u00edsticos caf\u00e9s y modernizados restaurantes que  atraen a los  turistas, como tambi\u00e9n las exposiciones, los sitios  hist\u00f3ricos  religiosos y los centros comerciales. Por eso vale citar los  lugares  m\u00e1s visitados: bulevar Charcas, entre Cnel. D\u00edaz y Salguero;  catedral  armenia cat\u00f3lica Nuestra Se\u00f1ora de Narek, Charcas 3529; iglesia  Nuestra  Se\u00f1ora de Guadalupe, tambi\u00e9n conocida como bas\u00edlica del  Esp\u00edritu  Santo, Mansilla y Medrano; iglesia Ortodoxa Rusa del  Patriarcado de  Mosc\u00fa, Bulnes 1743; Iglesia San Ildefonso, Guise 1941;  Museo y  Biblioteca Casa de Evaristo Carriego, Honduras 3784, y Alto  Palermo  Shopping, Santa Fe 3253.<\/p>\n<p><strong>Juan Manuel Raimundo, 16 de abril de 2011<br \/>\nPublicado por La Naci\u00f3n.<br \/>\n<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En torno de la tradicional parroquia, frente a la plaza G\u00fcemes, el crecimiento no se detiene y extiende sus l\u00edmites con alrededor de 30 proyectos de diversa magnitud. El precio de la incidencia de los terrenos ronda los 700 d\u00f3lares el m2, pero puede alcanzar hasta 1100. Cuando los vecinos remozaron con mucho verde el &hellip; <\/p>\n<p class=\"link-more\"><a href=\"http:\/\/blog.topinmobiliario.com\/index.php\/palermo-fuerte-identidad\/\" class=\"more-link\">Segu\u00ed leyendo<span class=\"screen-reader-text\"> &#8220;Palermo Fuerte identidad&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":3313,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[11],"tags":[91],"_links":{"self":[{"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/posts\/3310"}],"collection":[{"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/comments?post=3310"}],"version-history":[{"count":5,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/posts\/3310\/revisions"}],"predecessor-version":[{"id":3315,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/posts\/3310\/revisions\/3315"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/media\/3313"}],"wp:attachment":[{"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/media?parent=3310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/categories?post=3310"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/tags?post=3310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}