{"id":7096,"date":"2014-10-08T07:26:25","date_gmt":"2014-10-08T10:26:25","guid":{"rendered":"http:\/\/blog.topinmobiliario.com\/?p=7096"},"modified":"2014-10-08T08:13:06","modified_gmt":"2014-10-08T11:13:06","slug":"avenida-de-mayo-una-arteria-con-el-esplendor-intacto","status":"publish","type":"post","link":"http:\/\/blog.topinmobiliario.com\/index.php\/avenida-de-mayo-una-arteria-con-el-esplendor-intacto\/","title":{"rendered":"Avenida de mayo &#8211; Una arteria con el esplendor intacto"},"content":{"rendered":"<p><strong>Las oficinas se alquilan por mes entre los 10 y 16 d\u00f3lares por m2; los locales, entre los 18 y 22 d\u00f3lares por m2.<\/strong><\/p>\n<p>La Avenida de Mayo est\u00e1 flanqueada por dos de las construcciones m\u00e1s emblem\u00e1ticas del pa\u00eds: el Congreso de la Naci\u00f3n y la Casa Rosada se divisan desde all\u00ed, con s\u00f3lo mover la cabeza hacia un lado u otro. Esta corta, pero importante arteria porte\u00f1a fue y es testigo silencioso de nuestra historia, ya que vivi\u00f3 el crecimiento de la ciudad, los cambios sociales y pol\u00edticos que transcurrieron y siguen desarroll\u00e1ndose en la actualidad, adem\u00e1s de diversas muestras culturales que se llevan adelante aqu\u00ed.<\/p>\n<p>&#8220;Esta v\u00eda es un cl\u00e1sico con sus edificios franceses, confiter\u00edas como el Tortoni, el Palacio Barolo, el edificio de La Inmobiliaria, el hotel Castelar, el edificio del diario La Prensa y otros de gran se\u00f1or\u00edo que se mantienen en muy buen estado con sus c\u00fapulas y las grandiosas entradas&#8221;, coment\u00f3 Ricardo Vinelli, titular de Vinelli Inmobiliaria.<\/p>\n<p>Un ejemplo es el Palacio Barolo, al 1300 de la Avenida de Mayo, un edificio representativo del esplendor de esta arteria, que hace referencia a la Divina Comedia, de Dante Alighieri. Inaugurado en 1923, hoy es un edificio de oficinas al que se puede acceder. &#8220;La oficina que ofrecemos es de, estimamos, 235 m2 cubiertos, sin cochera y en estado para hacerle mejoras. El Palacio ofrece, en general, unidades chicas para peque\u00f1os estudios o servicios. Este caso es muy especial por tratarse de un edificio muy simb\u00f3lico&#8221;, detall\u00f3 Cesar Cancellieri, de Fera Cancellieri, inmobiliaria que comercializa una oficina en el inmueble.<\/p>\n<p>Su arquitectura predominante es un claro signo de su \u00e9poca se\u00f1orial, donde las c\u00fapulas, las molduras, las fachadas esculpidas y las grandes puertas trabajadas, entre otros, eran la norma. Hoy, esta parte de la ciudad convive con construcciones modernas que marcan una clara diferencia de estilos. Adem\u00e1s cuenta con una buena conectividad por el Metrobus, otras l\u00edneas de colectivos que la rodean, el acceso a los subtes, lo que facilita su llegada con el resto de la ciudad.<\/p>\n<p>Con un mercado de oficinas con una vacancia que se estima entre un 5% para locales y de un 10 a 15% para oficinas, la demanda se conforma por estudios profesionales, administraciones, despachantes de aduana, oficinas comerciales, compa\u00f1\u00edas de seguros y algunas, pero pocas, multinacionales. Alejandro Bazet, consultor de Castro Cranwell &amp; Weiss, dijo: &#8220;Aunque hace un tiempo que no se producen, el fantasma de las manifestaciones desanima la radicaci\u00f3n de oficinas. La instalaci\u00f3n de hoteles en edificios antiguos es un cl\u00e1sico de la avenida&#8221;.<\/p>\n<p>Por su parte, Vinelli dijo: &#8220;Quien busca oficinas amplias en edificios de \u00e9poca encuentra, sobre esta avenida, espacios con menores expensas. Siempre hay interesados en alquiler este tipo de inmuebles donde se prioriza el edificio art d\u00e9co y la cercan\u00eda con la peatonal Florida y la Plaza Mayo. Tambi\u00e9n las expensas suelen ser mucho m\u00e1s baratas y eso se analiza en el momento del cierre de cualquier operaci\u00f3n, sea de venta como en un alquiler&#8221;.<!--more--><\/p>\n<p>Los locales, especialmente los gastron\u00f3micos, tambi\u00e9n tienen su punto fuerte, que se centra en el radio comprendido desde Per\u00fa hasta Tacuar\u00ed. Vinelli destac\u00f3: &#8220;Ubicarse con un local significa tener asegurado un caudal de clientela muy importante: las calles peatonales, el subte, la cercan\u00eda a Plaza Mayo y zona bancaria, la calle Florida, aseguran un buen rendimiento de cualquier local&#8221;.<\/p>\n<p>En cuanto a los valores, en el caso de las oficinas se sit\u00faan entre los 10 y 16 d\u00f3lares por m2 por mes, mientras que los locales comerciales se encuentran entre los 18 y 22 d\u00f3lares por m2.<\/p>\n<p><strong>En un inmueble tradicional<\/strong><\/p>\n<p>Otro caso, esta vez de un local comercial, se sit\u00faa en el edificio La Inmobiliaria, inmueble que data de 1910 y que est\u00e1 en Avenida de Mayo al 1400. En su planta baja, donde antes se encontraba un bar, hoy Farmacity abri\u00f3 un local, en el que realiz\u00f3 no s\u00f3lo una inversi\u00f3n para adecuarlo a su identidad, sino tambi\u00e9n para arreglar la fachada caracter\u00edstica, acordando los trabajos con el consorcio del edificio, que al mismo tiempo se encuentra en plena tarea de puesta en valor de toda su fachada bajo la Direcci\u00f3n de Patrimonio de la Ciudad. Adem\u00e1s se dedicaron a arreglos de los espacio comunes, lo que llev\u00f3 a que la puesta en valor y remodelaci\u00f3n se sit\u00fae en los 6500 pesos por m2, aproximadamente.<\/p>\n<p>&#8220;Son muchos los casos, por las caracter\u00edsticas de Buenos Aires, en que nos encontramos con edificios antiguos de valor cultural; muchos est\u00e1n bajo el r\u00e9gimen de patrimonio hist\u00f3rico, como el caso del edificio La Inmobiliaria. M\u00e1s all\u00e1 de cumplir la legislaci\u00f3n vigente en todas las ciudades donde tenemos presencia, siempre cuidamos el patrimonio, considerando que la mejor manera de insertarnos en un barrio es colaborar con el cuidado de su patrimonio arquitect\u00f3nico. La gente lo valora y nosotros sumamos nuestro grano de arena. Tuvimos la posibilidad de elegir un edificio valorado por el vecino, ayudar a recuperarlo y poder ofrecer el servicio integral de nuestras farmacias, sumado a la poes\u00eda nost\u00e1lgica que preservan sus paredes. Un verdadero privilegio&#8221;, destac\u00f3 Carlos De Tezanos Pinto, director de infraestructura y desarrollo de Farmacity.<\/p>\n<p>Por <strong>Azal\u00eda Rivero Pomarino<\/strong>, Lunes 1 de septiembre de 2014<br \/>\nPublicado en el suplemento\u00a0<strong>Inmuebles comerciales <\/strong>del diario\u00a0<strong>LA NACION<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las oficinas se alquilan por mes entre los 10 y 16 d\u00f3lares por m2; los locales, entre los 18 y 22 d\u00f3lares por m2. La Avenida de Mayo est\u00e1 flanqueada por dos de las construcciones m\u00e1s emblem\u00e1ticas del pa\u00eds: el Congreso de la Naci\u00f3n y la Casa Rosada se divisan desde all\u00ed, con s\u00f3lo mover &hellip; <\/p>\n<p class=\"link-more\"><a href=\"http:\/\/blog.topinmobiliario.com\/index.php\/avenida-de-mayo-una-arteria-con-el-esplendor-intacto\/\" class=\"more-link\">Segu\u00ed leyendo<span class=\"screen-reader-text\"> &#8220;Avenida de mayo &#8211; Una arteria con el esplendor intacto&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":7097,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[269,11,5],"tags":[388,21],"_links":{"self":[{"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/posts\/7096"}],"collection":[{"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/comments?post=7096"}],"version-history":[{"count":4,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/posts\/7096\/revisions"}],"predecessor-version":[{"id":7156,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/posts\/7096\/revisions\/7156"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/media\/7097"}],"wp:attachment":[{"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/media?parent=7096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/categories?post=7096"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/tags?post=7096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}