{"id":7788,"date":"2015-11-02T08:16:00","date_gmt":"2015-11-02T11:16:00","guid":{"rendered":"http:\/\/blog.topinmobiliario.com\/?p=7788"},"modified":"2015-11-02T09:47:46","modified_gmt":"2015-11-02T12:47:46","slug":"la-panamericana-siempre-atrae-los-negocios","status":"publish","type":"post","link":"http:\/\/blog.topinmobiliario.com\/index.php\/la-panamericana-siempre-atrae-los-negocios\/","title":{"rendered":"La Panamericana, siempre atrae los negocios"},"content":{"rendered":"<p><strong>Se elabor\u00f3 un relevamiento sobre las ventajas por estar cerca de esta autov\u00eda y el potencial que ofrece al mercado corporativo. De hecho, muchas empresas eligieron el horizonte norte en los \u00faltimos a\u00f1os.<\/strong><\/p>\n<p>La consultora Cushman &amp; Wakefield junto con el estudio de arquitectura Oficina Urbana presentaron el estudio Oportunidad de Panamericana: de tr\u00e1nsito a la pertenencia, sobre el submercado de oficinas. Se trata de  un an\u00e1lisis de los atributos y sobre el potencial de desarrollo de la zona que se inicia en Saavedra, en la Capital, y, va hacia los partidos de Vicente L\u00f3pez y San Isidro, con rumbo norte.<\/p>\n<p>&#8220;Sin buscarlo, esta v\u00eda gener\u00f3 un subproducto cada vez m\u00e1s potente: los centros habitacionales suburbanos, esos lugares que asisten a las personas que quieren trabajar en el centro de la ciudad y vivir en las afueras. Se fue poblando con funciones y actividades. Luego, comenz\u00f3 a ser un componente clave de la suburbanizaci\u00f3n en los noventa, y con su ampliaci\u00f3n, surgieron edificios de oficinas y se abri\u00f3 un nuevo paisaje. Este nuevo car\u00e1cter de los alrededores de la autopista fue espont\u00e1neo, desordenado y con limitada planificaci\u00f3n&#8221;, dijo el director General del Cushman &amp; Wakefield Argentina, Herman Faigenbaum.<\/p>\n<p>Seg\u00fan los datos de la firma, el stock de oficinas clase A en 2014, al stock base de 160.000 metros cuadrados se agregaron 20.000. En tanto, en el primer trimestre de 2015, para la clase A fue de 183.398 metros cuadrados; la clase B, 131.417 m2 (27 por ciento de la superficie de estos edificios est\u00e1 sobre las avenidas Dardo Rocha y Fondo de la Legua, en San Isidro); el precio alquiler pedido en d\u00f3lares de los clase A, es de 24 y de 17, para los clase B.<\/p>\n<div>&#8220;La radicaci\u00f3n de actividades en la Panamericana se da por la descompresi\u00f3n de la ciudad hacia la periferia. El desarrollo de oficinas parte de la normativa vigente pero sin un proyecto urban\u00edstico ordenado. Los edificios de oficinas tienen poca conexi\u00f3n urbana entre ellos y no hay un entorno ideal para desarrollar actividades complementarias a las  laborales y productivas que, potenciar\u00eda la creaci\u00f3n de una red social y urbana&#8221;, dijo el director de Oficina Urbana, Roberto Converti.<\/p>\n<figure id=\"attachment_7789\" aria-describedby=\"caption-attachment-7789\" style=\"width: 500px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" class=\"size-full wp-image-7789\" title=\"La Panamericana\" src=\"http:\/\/blog.topinmobiliario.com\/wp-content\/uploads\/2015\/10\/paname.jpg\" alt=\"\" width=\"500\" height=\"256\" srcset=\"http:\/\/blog.topinmobiliario.com\/wp-content\/uploads\/2015\/10\/paname.jpg 500w, http:\/\/blog.topinmobiliario.com\/wp-content\/uploads\/2015\/10\/paname-300x153.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><figcaption id=\"caption-attachment-7789\" class=\"wp-caption-text\">Para reafirmar el avance que concentra esta ruta, en 2014, circularon m\u00e1s de 360.000 autos por d\u00eda.<\/figcaption><\/figure>\n<\/div>\n<p><strong>Por distritos<\/strong><\/p>\n<p>El trabajo analiza el nuevo ciclo al que entra la zona, basado en las caracter\u00edsticas y normativas actuales y busca redirigir las inversiones p\u00fablicas y privadas para especializar el territorio y la producci\u00f3n de oficinas desde tres espacios concretos: el distrito Creativo, el del Conocimiento, y, el de la Innovaci\u00f3n.<\/p>\n<p>En cuanto al Creativo, est\u00e1 formado por oficinas (de una parcela) destinadas a profesionales de productoras de TV y agencias, dise\u00f1adores, arquitectos, publicidad, etc\u00e9tera. Va desde Dardo Rocha con Thames y Diego Carman con Fondo de la Legua y tiene un gran entorno verde y servicios de escala barrial.<\/p>\n<div id=\"eplAdDivcaja4\"><span> <\/span> <span> <\/span> <span> <\/span><\/div>\n<p>El del Conocimiento concentra en una misma parcela grandes edificios relacionados con el consumo masivo, servicios financieros y la producci\u00f3n industrial. Con buen dise\u00f1o, amenities propios, sistemas tecnol\u00f3gicos y de management. La superficie rentable de los complejos va de 10.000 a 50.000 metros cuadrados, con cocheras, grandes plantas y en un entorno mejorado.<\/p>\n<p>Mientras que en el de la Innovaci\u00f3n, funciona un centro de oficinas y servicios, est\u00e1 en el nodo entre la Avenida General Paz y la Panamericana, y articula como frontera entre la Capital y el Gran Buenos Aires. Con edificios inteligentes, alto grado de tecnolog\u00eda y valor agregado en management. Es un sector muy bueno y demandado por las empresas, con r\u00e1pidos accesos y mucho progreso de la construcci\u00f3n.<\/p>\n<p>Por <strong>Patricia Osuna Guti\u00e9rrez<\/strong><strong>, <\/strong>Lunes 5 de octubre de 2015<br \/>\nPublicado en el suplemento\u00a0<strong>Inmuebles Comerciales <\/strong>del diario\u00a0<strong>LA NACION<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se elabor\u00f3 un relevamiento sobre las ventajas por estar cerca de esta autov\u00eda y el potencial que ofrece al mercado corporativo. De hecho, muchas empresas eligieron el horizonte norte en los \u00faltimos a\u00f1os. La consultora Cushman &amp; Wakefield junto con el estudio de arquitectura Oficina Urbana presentaron el estudio Oportunidad de Panamericana: de tr\u00e1nsito a &hellip; <\/p>\n<p class=\"link-more\"><a href=\"http:\/\/blog.topinmobiliario.com\/index.php\/la-panamericana-siempre-atrae-los-negocios\/\" class=\"more-link\">Segu\u00ed leyendo<span class=\"screen-reader-text\"> &#8220;La Panamericana, siempre atrae los negocios&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":7789,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[420,11,5],"tags":[336],"_links":{"self":[{"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/posts\/7788"}],"collection":[{"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/comments?post=7788"}],"version-history":[{"count":5,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/posts\/7788\/revisions"}],"predecessor-version":[{"id":7828,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/posts\/7788\/revisions\/7828"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/media\/7789"}],"wp:attachment":[{"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/media?parent=7788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/categories?post=7788"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/tags?post=7788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}