{"id":8759,"date":"2017-03-07T12:57:36","date_gmt":"2017-03-07T15:57:36","guid":{"rendered":"http:\/\/blog.topinmobiliario.com\/?p=8759"},"modified":"2017-03-07T12:57:36","modified_gmt":"2017-03-07T15:57:36","slug":"inversiones-los-desarrolladores-tienen-en-la-mira-a-vaca-muerta","status":"publish","type":"post","link":"http:\/\/blog.topinmobiliario.com\/index.php\/inversiones-los-desarrolladores-tienen-en-la-mira-a-vaca-muerta\/","title":{"rendered":"Inversiones &#8211; Los desarrolladores tienen en la mira a Vaca Muerta"},"content":{"rendered":"<p><strong>El gobierno local dise\u00f1\u00f3 un masterpl\u00e1n que contempla la construcci\u00f3n de una ciudad de 30.000 habitantes en 2030; los emprendimientos en oferta.<\/p>\n<p><\/strong><\/p>\n<figure id=\"attachment_8760\" aria-describedby=\"caption-attachment-8760\" style=\"width: 620px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/blog.topinmobiliario.com\/wp-content\/uploads\/2017\/03\/propiedades-2359582w620.jpg\"><img loading=\"lazy\" class=\"size-full wp-image-8760\" title=\"propiedades-2359582w620\" src=\"http:\/\/blog.topinmobiliario.com\/wp-content\/uploads\/2017\/03\/propiedades-2359582w620.jpg\" alt=\"\" width=\"620\" height=\"348\" srcset=\"http:\/\/blog.topinmobiliario.com\/wp-content\/uploads\/2017\/03\/propiedades-2359582w620.jpg 620w, http:\/\/blog.topinmobiliario.com\/wp-content\/uploads\/2017\/03\/propiedades-2359582w620-300x168.jpg 300w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/><\/a><figcaption id=\"caption-attachment-8760\" class=\"wp-caption-text\">Los edificios de Altos de A\u00f1elo est\u00e1n terminados y permiten invertir a trav\u00e9s del crownfunding. <\/figcaption><\/figure>\n<p>El inmobiliario es, ante todo, un negocio de expectativas. Y as\u00ed lo expresan los desarrolladores que trabajan en la zona de A\u00f1elo, en Neuqu\u00e9n, m\u00e1s conocida como Vaca Muerta. Hoy, despu\u00e9s de un a\u00f1o pr\u00e1cticamente en suspenso para la industria petrolera a escala local y con un mercado dif\u00edcil a nivel internacional, las perspectivas de mejoras en el sector est\u00e1n latentes y los proyectos en la zona, dicen, han comenzado a recobrar impulso.<\/p>\n<p>En enero, el presidente Mauricio Macri anunci\u00f3 el plan de explotaci\u00f3n de Vaca Muerta, que incluye al gobierno provincial del Movimiento Popular Neuquino, a los gremios petroleros y a las empresas del sector. Macri plante\u00f3 un compromiso de inversiones por US$ 5000 millones para este primer a\u00f1o y asegur\u00f3 que el acuerdo generar\u00e1 &#8220;una verdadera revoluci\u00f3n del trabajo&#8221;.<\/p>\n<p>La noticia gener\u00f3 una ola de confianza sobre el potencial de los ladrillos en la zona. El empresario Dami\u00e1n Lopo es director de Crowdium, la empresa de crowdfunding inmobiliario que tiene en su cartera de inversiones a Altos de A\u00f1elo 1. Uno de los cuatro edificios terminados que conforman el proyecto. La compa\u00f1\u00eda invirti\u00f3 $ 20 millones en la edificaci\u00f3n que cuenta con 15 unidades. &#8220;Es uno de los primeros desarrollos terminados en la localidad&#8221;, destaca el ejecutivo que en dos semanas cierra el proceso de inversi\u00f3n. &#8220;Fue tanta la demanda que planeamos el lanzamiento de Altos de A\u00f1elo 2, otro de los edificios terminados&#8221;, agrega. En este \u00faltimo caso planea reunir alrededor de $ 35 millones. Lopo desembarc\u00f3 en el \u00e1rea antes de los anuncios presidenciales que involucraron al sector energ\u00e9tico. Las perspectivas de la zona anticipan un futuro que se intuye auspicioso. &#8220;En los negocios financieros al igual que en el mercado inmobiliario, si el inversor quiere un buen upside de su inversi\u00f3n tiene que comprar con el rumor y vender con la noticia, como dice el dicho&#8221;, afirma Lopo y profundiza: &#8220;Hoy el petr\u00f3leo se encuentra en el m\u00ednimo hist\u00f3rico, lo cual presupone una menor demanda, y nos permiti\u00f3 con negociar mejores condiciones de compra. Paralelamente y para mitigar el riesgo, mientras el mercado del petr\u00f3leo se reacomoda, logramos negociar un contrato de alquiler por dos a\u00f1os a US$ 25\/m2, un precio superior a lo que se paga en Puerto Madero por algunas oficinas&#8221;. Es decir, quien participa del crownfunding ingresa al negocio con renta desde el comienzo porque las unidades ya est\u00e1n colocadas. Adem\u00e1s para que el inversor no afronte los riesgos constructivos, la estrategia de Lopo fue comprar un complejo de departamentos, terminados, y amoblados. &#8220;Hay demanda de viviendas tanto para operarios como para ejecutivos por la cantidad de empresas instaladas&#8221;, agrega.<\/p>\n<p>Otro dato, el valor de venta del m2 ronda los US$ 2300. &#8220;En nuestro caso como compramos por mayor pagamos US$ 1825\/m2, con un descuento del 15 por ciento sobre el precio de lista con un contrato de alquiler en d\u00f3lares asegurado&#8221;, aclara el ejecutivo.<\/p>\n<p>El directivo anticipa que en los pr\u00f3ximos dos a\u00f1os los valores en torno al petr\u00f3leo van a fluctuar: &#8220;En el momento en que veamos que el precio levanta y la demanda crezca, podemos pensar en vender en un valor superior al actual, motivo por el cual creemos que es altamente probable que hagamos un gran negocio en la salida, tambi\u00e9n&#8221;.<\/p>\n<p>Lopo conf\u00eda en la forma que est\u00e1 estructurado su producto, en un &#8220;mercado pr\u00e1cticamente sin oferta y con una demanda creciente y a punto de explotar&#8221;. El crownfunding da la posibilidad que quien no tenga el ciento por ciento del capital de lo que vale una unidad, pueda participar. &#8220;Es una buena alternativa en un mercado en el que menos del uno por ciento de la poblaci\u00f3n tiene m\u00e1s de US$ 150.000 para invertir en inmuebles&#8221;, relata y estima que los compradores est\u00e1n invirtiendo un promedio de $ 500.000. Aunque pueden ingresar desde $ 25.000. &#8220;El sistema est\u00e1 controlado por una fiduciaria regulada por la Comisi\u00f3n Nacional de Valores&#8221;, aclara. En la empresa subrayan que se trata de una inversi\u00f3n &#8220;d\u00f3lar linked&#8221; donde el escenario de una cotizaci\u00f3n de esta divisa a $ 23 en dos a\u00f1os &#8220;es bastante probable, por lo que se espera una revalorizaci\u00f3n del activo, que calculan entre el 25 y 35 por ciento&#8221;. Adem\u00e1s, enfatiza, se trata de un producto que no est\u00e1 sujeto a las fluctuaciones financieras de un mundo globalizado. &#8220;En el contexto actual, el inversor obtiene una renta de 15 por ciento anual en d\u00f3lares, pero si el precio del petr\u00f3leo dentro de los pr\u00f3ximos a\u00f1os volviera a subir a niveles l\u00f3gicos, la explosi\u00f3n en la demanda y la baja oferta que hay en Vaca Muerta, generar\u00eda ganancias extraordinarias&#8221;, detalla. Vaca Muerta es la cuarta reserva de petr\u00f3leo y gas del mundo, motivo por el cual su poblaci\u00f3n creci\u00f3 el mil por ciento en los \u00faltimos a\u00f1os y lo seguir\u00e1 haciendo.<\/p>\n<p><strong>El futuro promete<\/strong><\/p>\n<p>A trav\u00e9s del mismo sistema, otra compa\u00f1\u00eda ha apostado a la localidad neuquina. Se trata de Crowdfunding Inmobiliario Argentino, la empresa que posee el emprendimiento Las Rosas con una oferta de d\u00faplex de 70 m2 que se entregan llave en mano. &#8220;Durante 2016, el proyecto estuvo sin grandes movimientos y un poco retra\u00eddo, pero luego de los anuncios realizados por las autoridades provinciales, nacionales y el sindicato de petr\u00f3leo se est\u00e1n comenzando a reactivar los pedidos de nuevos d\u00faplex y los contratos de alquiler con petroleros, lo que auspicia un buen 2017&#8221;, coinciden Miguel \u00c1ngel Alesandro, CEO de y Gustavo Gonz\u00e1lez, martillero de Habitar Inmobiliaria.<\/p>\n<p>Consultados por la rentabilidad del negocio, los entrevistados afirman que &#8220;si bien los valores relativos a los alquileres respecto a lo invertido en ladrillos sufrieron una baja porcentual. A\u00f1elo aun sigue siendo muy beneficioso respecto a otras zonas del pa\u00eds&#8221;. \u00bfEl target del inversor? &#8220;Todo ahorrista dispuesto a invertir, una de las metodolog\u00edas que se ofrece es la administraci\u00f3n de la renta sobre los d\u00faplex por lo cual la oportunidad es doblemente tentadora&#8221;, afirman, destacando que la inversi\u00f3n no se enfoque s\u00f3lo en el p\u00fablico local.<\/p>\n<p>Un dato no menor es que la intendencia de A\u00f1elo, dise\u00f1\u00f3 un masterpl\u00e1n con un objetivo de m\u00e1xima prioridad: construir una ciudad de 30.000 habitantes en 2030, para lo cual deber\u00e1 ampliar de forma significativa la oferta de servicios de salud, educaci\u00f3n y vivienda, as\u00ed como fomentar la radicaci\u00f3n de industrias en la regi\u00f3n. Desde el canal de ventas, Marcelo Vi\u00f1as, titular de la inmobiliaria hom\u00f3nima apunta que el mercado inmobiliario en A\u00f1elo registr\u00f3 el &#8220;parate&#8221; de la industria petrolera durante el a\u00f1o que pas\u00f3. Al mismo tiempo, reconoce que se estuvo produciendo un reacomodamiento en los valores de los alquileres, estimados en relaci\u00f3n a los sueldos que cobraban los ejecutivos del sector y que, seg\u00fan los acuerdos homologados hace unos pocos d\u00edas, sufrieron reacomodamientos. As\u00ed y todo, se\u00f1ala quien adem\u00e1s es titular del colegio de martilleros local, las oportunidades en toda Neuqu\u00e9n son grandes: &#8220;Hay un d\u00e9ficit de 60.000 viviendas a nivel provincial, por lo que siempre habr\u00e1 demanda&#8221;, puntualiza Vi\u00f1as, destacando que entre el 60 y 65 por ciento de la poblaci\u00f3n neuquina tiene menos de 30 a\u00f1os, lo que convierte a la provincia en una plaza pujante. &#8220;Si bien se habl\u00f3 mucho de Vaca Muerta, hay otras localidades que vivieron un boom. Tal es el caso de Plottier y Centenario -a 15 km de la ciudad capital- cuyas poblaciones se incrementaron un 100 por ciento en los \u00faltimos a\u00f1os&#8221;, finaliza.<\/p>\n<p>Por\u00a0<strong>Victoria Aranda<\/strong>, S\u00e1bado 11 de febrero de 2017<br \/>\nPublicado en el suplemento\u00a0<strong>Propiedades &amp; Countries <\/strong>del diario\u00a0<strong>LA NACION<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobierno local dise\u00f1\u00f3 un masterpl\u00e1n que contempla la construcci\u00f3n de una ciudad de 30.000 habitantes en 2030; los emprendimientos en oferta. El inmobiliario es, ante todo, un negocio de expectativas. Y as\u00ed lo expresan los desarrolladores que trabajan en la zona de A\u00f1elo, en Neuqu\u00e9n, m\u00e1s conocida como Vaca Muerta. Hoy, despu\u00e9s de un &hellip; <\/p>\n<p class=\"link-more\"><a href=\"http:\/\/blog.topinmobiliario.com\/index.php\/inversiones-los-desarrolladores-tienen-en-la-mira-a-vaca-muerta\/\" class=\"more-link\">Segu\u00ed leyendo<span class=\"screen-reader-text\"> &#8220;Inversiones &#8211; Los desarrolladores tienen en la mira a Vaca Muerta&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":8760,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[599,5],"tags":[290,669],"_links":{"self":[{"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/posts\/8759"}],"collection":[{"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/comments?post=8759"}],"version-history":[{"count":3,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/posts\/8759\/revisions"}],"predecessor-version":[{"id":8763,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/posts\/8759\/revisions\/8763"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/media\/8760"}],"wp:attachment":[{"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/media?parent=8759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/categories?post=8759"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/tags?post=8759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}