{"id":9278,"date":"2018-01-17T14:08:11","date_gmt":"2018-01-17T17:08:11","guid":{"rendered":"http:\/\/blog.topinmobiliario.com\/?p=9278"},"modified":"2018-01-17T16:11:29","modified_gmt":"2018-01-17T19:11:29","slug":"que-construir-en-el-fondo-de-la-vivienda","status":"publish","type":"post","link":"http:\/\/blog.topinmobiliario.com\/index.php\/que-construir-en-el-fondo-de-la-vivienda\/","title":{"rendered":"Qu\u00e9 construir en el fondo de la vivienda"},"content":{"rendered":"<p><strong>Existe un p\u00fablico para cada opci\u00f3n: el espacio disponible, el mantenimiento y los costos son factores clave para la elecci\u00f3n; las ventajas y desventajas de cada alternativa.<\/strong><\/p>\n<p><strong> <\/strong><\/p>\n<p><strong> <\/strong><\/p>\n<p><strong><strong>A favor<\/strong><\/strong><\/p>\n<p><strong><strong> <\/strong><\/strong><\/p>\n<p><strong><strong><a href=\"http:\/\/blog.topinmobiliario.com\/wp-content\/uploads\/2018\/01\/propiedades-2577332w620.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-9279\" title=\"propiedades-2577332w620\" src=\"http:\/\/blog.topinmobiliario.com\/wp-content\/uploads\/2018\/01\/propiedades-2577332w620.jpg\" alt=\"\" width=\"620\" height=\"348\" srcset=\"http:\/\/blog.topinmobiliario.com\/wp-content\/uploads\/2018\/01\/propiedades-2577332w620.jpg 620w, http:\/\/blog.topinmobiliario.com\/wp-content\/uploads\/2018\/01\/propiedades-2577332w620-300x168.jpg 300w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/><\/a><br \/>\n<\/strong><\/strong><\/p>\n<p><strong>Piletas.<\/strong> A la hora de comprar una casa o edificar una vivienda muchas familias eligen dejar un lugar del terreno reservado para construir una piscina. Estos espacios en muchos casos se convierten en la vedette de los fondos no s\u00f3lo durante las jornadas diurnas de primavera y verano sino tambi\u00e9n durante las noches del resto del a\u00f1o. &#8220;Nosotros para hacer de ella un espacio vistoso le colocamos iluminaci\u00f3n interior que no s\u00f3lo nos permite poder utilizarla cuando ya no hay luz natural sino tambi\u00e9n la viste por las noches, d\u00e1ndole un toque particular al fondo de nuestra casa durante los 365 d\u00edas del a\u00f1o&#8221;, explica Mar\u00eda Fernanda C., una vecina de Nordelta. Seg\u00fan el m\u00e9todo constructivo que se elija una pileta de hormig\u00f3n de 8 por 4 metros y de 1,80 de profundidad m\u00e1xima puede costar desde los $ 150.000 y realizarse en tan s\u00f3lo 15 d\u00edas con un gasto de mantenimiento semanal de $1000.<\/p>\n<p><strong>Jardines.<\/strong> En los \u00faltimos tiempos los espacios verdes que suelen nacer en el fondo de las viviendas se presentan como continuaciones naturales tanto de livings como de comedores, aport\u00e1ndole una importante extensi\u00f3n natural de los espacios interiores. &#8220;El equilibrio entre el interior y el exterior es fundamental&#8221;, afirma Mat\u00edas Goyenechea, paisajista y titular del estudio a su nombre.<\/p>\n<p>En estos sectores es prioritario no dejar nada librado al azar, una buena elecci\u00f3n de especies vegetales no s\u00f3lo responde a fines est\u00e9ticos sino que adem\u00e1s colabora con el estado de \u00e1nimo de los habitantes de esa vivienda.  Otra de las ventajas de este tipo de sitios es que se pueden disfrutar, a diferencia de las piscinas, durante todo el a\u00f1o y hasta con un menor costo de mantenimiento  -desde los $ 750 mensuales-. &#8220;Se puede  crear algo accesible y de bajo costo de conservaci\u00f3n, pero adem\u00e1s es importante valorar y preservar los rasgos locales con su correlato cultural, respetando lo aut\u00f3ctono y propio de cada sitio&#8221;, comenta el paisajista Carlos Thays.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><\/p>\n<p><strong>En contra<\/strong><\/p>\n<p><strong> <\/strong><\/p>\n<p><strong><a href=\"http:\/\/blog.topinmobiliario.com\/wp-content\/uploads\/2018\/01\/propiedades-2577333w640.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-9280\" title=\"propiedades-2577333w640\" src=\"http:\/\/blog.topinmobiliario.com\/wp-content\/uploads\/2018\/01\/propiedades-2577333w640.jpg\" alt=\"\" width=\"640\" height=\"360\" srcset=\"http:\/\/blog.topinmobiliario.com\/wp-content\/uploads\/2018\/01\/propiedades-2577333w640.jpg 640w, http:\/\/blog.topinmobiliario.com\/wp-content\/uploads\/2018\/01\/propiedades-2577333w640-300x168.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a><br \/>\n<\/strong><\/p>\n<p><strong>Piletas.<\/strong> Las piscinas en muchas ocasiones se convierten en el punto de reuni\u00f3n de conocidos, amigos y familiares, rompiendo con la tranquilidad del hogar. &#8220;Cuando se tratan de reuniones con mucha gente, resulta estresante estar pendiente de los ni\u00f1os&#8221;, agrega Mar\u00eda Fernanda. En las piletas convencionales hay que tener cuidado con los bordes: suelen ser traicioneros y provocar ca\u00eddas para ello es importante contar con suelos at\u00e9rmicos y antideslizantes.<\/p>\n<p><strong>Jardines.<\/strong> Para que la construcci\u00f3n de estos espacios sea equilibrada es preciso convocar a profesionales. Estos espacios demandan muchas horas de trabajo, gran conocimiento sobre bot\u00e1nica y un cuidado meticuloso. En muchas ocasiones es preciso contratar un profesional sobre el tema para poder tener un mantenimiento apropiado.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><\/p>\n<p><strong>Check-List<\/strong><\/p>\n<p><strong>Piletas.<\/strong> Antes elegir el lugar donde construir la pileta es importante observar tanto durante la primavera como el verano el recorrido que realiza en sol en el parque para evitar zonas de sombras.<\/p>\n<p>Si el hogar es frecuentado por ni\u00f1os peque\u00f1os es  importante contar con normas de seguridad alrededor del espejo de agua, como rejas y hasta cubrepiletas. Para los que quieren darle un toque especial a sus piscinas existe Agua de Piedra, un revestimiento calc\u00e1reo premium para transformar y embellecer el interior de la pileta aport\u00e1ndole un aspecto que va desde el verde del mar hasta el azul del oc\u00e9ano.<\/p>\n<p><strong>Jardines.<\/strong> Es importante hacer una buena planificaci\u00f3n del lugar para poder aprovechar el espacio; cuando se trata de sitios grandes se puede jugar con las escalas y las perspectivas.<\/p>\n<p>A la hora de dise\u00f1ar un jard\u00edn es importante la nivelaci\u00f3n del suelo y tener en cuenta la calidad de la tierra que se utilizar\u00e1 en el lugar. La mayor\u00eda de los arbustos que se utilizan como cerco son de crecimiento r\u00e1pido y deben colocarse uno cada metro cuadrado, si la casa cuenta con alambrado ol\u00edmpico puede revestirse con enredaderas. Mantener un jard\u00edn mensual tiene un costo promedio que ronda entre 1500 y 3000 pesos mensuales.<\/p>\n<p>Por <strong>Leandro Murciego<\/strong>, S\u00e1bado 25 de noviembre de 2017<br \/>\nPublicado en el suplemento\u00a0<strong>Propiedades &amp; Countries <\/strong>del diario\u00a0<strong>LA NACION<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Existe un p\u00fablico para cada opci\u00f3n: el espacio disponible, el mantenimiento y los costos son factores clave para la elecci\u00f3n; las ventajas y desventajas de cada alternativa. A favor Piletas. A la hora de comprar una casa o edificar una vivienda muchas familias eligen dejar un lugar del terreno reservado para construir una piscina. Estos &hellip; <\/p>\n<p class=\"link-more\"><a href=\"http:\/\/blog.topinmobiliario.com\/index.php\/que-construir-en-el-fondo-de-la-vivienda\/\" class=\"more-link\">Segu\u00ed leyendo<span class=\"screen-reader-text\"> &#8220;Qu\u00e9 construir en el fondo de la vivienda&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":9279,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[599,5],"tags":[666,410],"_links":{"self":[{"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/posts\/9278"}],"collection":[{"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/comments?post=9278"}],"version-history":[{"count":5,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/posts\/9278\/revisions"}],"predecessor-version":[{"id":9284,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/posts\/9278\/revisions\/9284"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/media\/9279"}],"wp:attachment":[{"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/media?parent=9278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/categories?post=9278"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/blog.topinmobiliario.com\/index.php\/wp-json\/wp\/v2\/tags?post=9278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}